{"id":34378,"date":"2024-02-27T08:21:23","date_gmt":"2024-02-27T07:21:23","guid":{"rendered":"https:\/\/www.alternatievemiddelen.nl\/?post_type=product&#038;p=34378"},"modified":"2026-05-04T12:02:54","modified_gmt":"2026-05-04T10:02:54","slug":"breizh-keltisch-zeezout-fijn-400gr","status":"publish","type":"product","link":"https:\/\/www.alternatievemiddelen.nl\/de\/produkte\/breizh-keltisches-meersalz-fein-400gr\/","title":{"rendered":"Breizh Keltisches Meersalz fein 400 gr im Beutel"},"content":{"rendered":"<p>Breizh Keltisches Meersalz fein 400 gr im Beutel<\/p>\n<p>Handgeerntet und handwerklich hergestellt. Bei niedriger Temperatur gemahlen und getrocknet. Unverarbeitet und frei von Zusatzstoffen. Nat\u00fcrlich rein und mineralstoffreich.<\/p>\n<p><u><b>Inhaltsstoffe<\/b><\/u><br \/>\n100% Meersalz<\/p>\n<p><u>Provenienz:<\/u> Frankreich<\/p>\n<p><u><b>Verwenden Sie<\/b><\/u><br \/>\nVerwenden Sie es als Speisesalz f\u00fcr alle Ihre Gerichte.<br \/>\nDieses sehr mineralstoffreiche keltische Feinmeersalz ist ein Gew\u00fcrz f\u00fcr viele Gerichte.<\/p>\n<p>Trocken und versiegelt aufbewahren.<\/p>","protected":false},"excerpt":{"rendered":"<p>Breizh keltisches Meersalz fein 400 gr im Beutel - Handgeerntet und handwerklich hergestellt. Gemahlen und getrocknet bei niedriger Temperatur. Nat\u00fcrlich rein und mineralreich.<\/p>","protected":false},"featured_media":31089,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3042,3153],"product_tag":[3154,3155,3156],"merk":[3438],"class_list":{"0":"post-34378","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gezonde-voedingsmiddelen","7":"product_cat-overige-gezonde-voedingsmiddelen","8":"product_tag-breizh","9":"product_tag-breizh-keltisch-zeezout-fijn-400-gr","10":"product_tag-keltisch-zeezout","11":"merk-breizh","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Breizh keltisch zeezout fijn 400 gr in zak - Alternatievemiddelen.nl<\/title>\n<meta name=\"description\" content=\"Breizh keltisch zeezout fijn 400 gr in zak - Handmatig en ambachtelijk geoogst. Gemalen &amp; gedroogd op lage temperatuur. Natuurzuiver en mineraalrijk.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/product\/34378\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Breizh keltisch zeezout fijn 400 gr in zak - Alternatievemiddelen.nl\" \/>\n<meta property=\"og:description\" content=\"Breizh keltisch zeezout fijn 400 gr in zak - Handmatig en ambachtelijk geoogst. Gemalen &amp; gedroogd op lage temperatuur. Natuurzuiver en mineraalrijk.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alternatievemiddelen.nl\/de\/produkte\/breizh-keltisches-meersalz-fein-400gr\/\" \/>\n<meta property=\"og:site_name\" content=\"Alternatievemiddelen.nl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alternatievemiddelen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T10:02:54+00:00\" \/>\n<meta property=\"og:image\" content=\"\/wp-content\/uploads\/2023\/12\/Breizh-keltisch-zeezout-fijn-400gr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/\",\"url\":\"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/\",\"name\":\"Breizh keltisch zeezout fijn 400 gr in zak - Alternatievemiddelen.nl\",\"isPartOf\":{\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.alternatievemiddelen.nl\/wp-content\/uploads\/2023\/12\/Breizh-keltisch-zeezout-fijn-400gr.jpg\",\"datePublished\":\"2024-02-27T07:21:23+00:00\",\"dateModified\":\"2026-05-04T10:02:54+00:00\",\"description\":\"Breizh keltisch zeezout fijn 400 gr in zak - Handmatig en ambachtelijk geoogst. Gemalen & gedroogd op lage temperatuur. Natuurzuiver en mineraalrijk.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/#primaryimage\",\"url\":\"https:\/\/www.alternatievemiddelen.nl\/wp-content\/uploads\/2023\/12\/Breizh-keltisch-zeezout-fijn-400gr.jpg\",\"contentUrl\":\"https:\/\/www.alternatievemiddelen.nl\/wp-content\/uploads\/2023\/12\/Breizh-keltisch-zeezout-fijn-400gr.jpg\",\"width\":600,\"height\":800,\"caption\":\"Breizh keltisch zeezout zak\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.alternatievemiddelen.nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\/\/www.alternatievemiddelen.nl\/producten\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Breizh keltisch zeezout fijn 400 gr in zak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/#website\",\"url\":\"https:\/\/www.alternatievemiddelen.nl\/\",\"name\":\"Alternatievemiddelen.nl\",\"description\":\"Webshop met gezonde, duurzame en ecologische alternatieve mogelijkheden in de hedendaagse levenstijl. Alles uit eigen ervaring.\",\"publisher\":{\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/#organization\"},\"alternateName\":\"Alternatieve Middelen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.alternatievemiddelen.nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/#organization\",\"name\":\"Alternatievemiddelen.nl\",\"alternateName\":\"Alternatieve Middelen\",\"url\":\"https:\/\/www.alternatievemiddelen.nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.alternatievemiddelen.nl\/wp-content\/uploads\/2023\/10\/alternatievemiddelen-PNG-logo.png\",\"contentUrl\":\"https:\/\/www.alternatievemiddelen.nl\/wp-content\/uploads\/2023\/10\/alternatievemiddelen-PNG-logo.png\",\"width\":6400,\"height\":3062,\"caption\":\"Alternatievemiddelen.nl\"},\"image\":{\"@id\":\"https:\/\/www.alternatievemiddelen.nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/alternatievemiddelen\",\"https:\/\/www.instagram.com\/alternatievemiddelen.nl\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Breizh keltisch zeezout fijn 400 gr in zak - Alternatievemiddelen.nl","description":"Breizh keltisch zeezout fijn 400 gr in zak - Handmatig en ambachtelijk geoogst. Gemalen & gedroogd op lage temperatuur. Natuurzuiver en mineraalrijk.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/product\/34378","og_locale":"de_DE","og_type":"article","og_title":"Breizh keltisch zeezout fijn 400 gr in zak - Alternatievemiddelen.nl","og_description":"Breizh keltisch zeezout fijn 400 gr in zak - Handmatig en ambachtelijk geoogst. Gemalen & gedroogd op lage temperatuur. Natuurzuiver en mineraalrijk.","og_url":"https:\/\/www.alternatievemiddelen.nl\/de\/produkte\/breizh-keltisches-meersalz-fein-400gr\/","og_site_name":"Alternatievemiddelen.nl","article_publisher":"https:\/\/www.facebook.com\/alternatievemiddelen","article_modified_time":"2026-05-04T10:02:54+00:00","og_image":[{"width":600,"height":800,"url":"\/wp-content\/uploads\/2023\/12\/Breizh-keltisch-zeezout-fijn-400gr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/","url":"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/","name":"Breizh keltisch zeezout fijn 400 gr in zak - Alternatievemiddelen.nl","isPartOf":{"@id":"https:\/\/www.alternatievemiddelen.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/#primaryimage"},"image":{"@id":"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alternatievemiddelen.nl\/wp-content\/uploads\/2023\/12\/Breizh-keltisch-zeezout-fijn-400gr.jpg","datePublished":"2024-02-27T07:21:23+00:00","dateModified":"2026-05-04T10:02:54+00:00","description":"Breizh keltisch zeezout fijn 400 gr in zak - Handmatig en ambachtelijk geoogst. Gemalen & gedroogd op lage temperatuur. Natuurzuiver en mineraalrijk.","breadcrumb":{"@id":"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/#primaryimage","url":"https:\/\/www.alternatievemiddelen.nl\/wp-content\/uploads\/2023\/12\/Breizh-keltisch-zeezout-fijn-400gr.jpg","contentUrl":"https:\/\/www.alternatievemiddelen.nl\/wp-content\/uploads\/2023\/12\/Breizh-keltisch-zeezout-fijn-400gr.jpg","width":600,"height":800,"caption":"Breizh keltisch zeezout zak"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alternatievemiddelen.nl\/producten\/breizh-keltisch-zeezout-fijn-400gr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alternatievemiddelen.nl\/"},{"@type":"ListItem","position":2,"name":"Producten","item":"https:\/\/www.alternatievemiddelen.nl\/producten\/"},{"@type":"ListItem","position":3,"name":"Breizh keltisch zeezout fijn 400 gr in zak"}]},{"@type":"WebSite","@id":"https:\/\/www.alternatievemiddelen.nl\/#website","url":"https:\/\/www.alternatievemiddelen.nl\/","name":"Alternatievemiddelen.nl","description":"Webshop met gezonde, duurzame en ecologische alternatieve mogelijkheden in de hedendaagse levenstijl. Alles uit eigen ervaring.","publisher":{"@id":"https:\/\/www.alternatievemiddelen.nl\/#organization"},"alternateName":"Alternatieve Middelen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alternatievemiddelen.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.alternatievemiddelen.nl\/#organization","name":"Alternatievemiddelen.nl","alternateName":"Alternatieve Middelen","url":"https:\/\/www.alternatievemiddelen.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.alternatievemiddelen.nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.alternatievemiddelen.nl\/wp-content\/uploads\/2023\/10\/alternatievemiddelen-PNG-logo.png","contentUrl":"https:\/\/www.alternatievemiddelen.nl\/wp-content\/uploads\/2023\/10\/alternatievemiddelen-PNG-logo.png","width":6400,"height":3062,"caption":"Alternatievemiddelen.nl"},"image":{"@id":"https:\/\/www.alternatievemiddelen.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alternatievemiddelen","https:\/\/www.instagram.com\/alternatievemiddelen.nl\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/product\/34378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/comments?post=34378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/media\/31089"}],"wp:attachment":[{"href":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/media?parent=34378"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/product_brand?post=34378"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/product_cat?post=34378"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/product_tag?post=34378"},{"taxonomy":"merk","embeddable":true,"href":"https:\/\/www.alternatievemiddelen.nl\/de\/wp-json\/wp\/v2\/merk?post=34378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}